{"id":598,"count":81,"description":"","link":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/","name":"SonicWall","slug":"sonicwall","taxonomy":"category","parent":597,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SonicWall Archives - Firewalls.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SonicWall Archives - Firewalls.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/\" \/>\n<meta property=\"og:site_name\" content=\"Firewalls.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@firewallscom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/category\\\/firewalls\\\/sonicwall\\\/\",\"url\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/category\\\/firewalls\\\/sonicwall\\\/\",\"name\":\"SonicWall Archives - Firewalls.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/category\\\/firewalls\\\/sonicwall\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/category\\\/firewalls\\\/sonicwall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firewalls\",\"item\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/category\\\/firewalls\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SonicWall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/\",\"name\":\"Firewalls.com\",\"description\":\"Your Home For Cyber Security News, Stories, &amp; Tutorials\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/#organization\",\"name\":\"Firewalls.com\",\"url\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/BrandedLogo-TagLineBelow.png\",\"contentUrl\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/BrandedLogo-TagLineBelow.png\",\"width\":365,\"height\":85,\"caption\":\"Firewalls.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.firewalls.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/firewallscom\",\"https:\\\/\\\/x.com\\\/firewallscom\",\"https:\\\/\\\/www.linkedin.com\\\/company-beta\\\/1439857\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/firewallsDotCom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SonicWall Archives - Firewalls.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/","og_locale":"en_US","og_type":"article","og_title":"SonicWall Archives - Firewalls.com","og_url":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/","og_site_name":"Firewalls.com","twitter_card":"summary_large_image","twitter_site":"@firewallscom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/","url":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/","name":"SonicWall Archives - Firewalls.com","isPartOf":{"@id":"https:\/\/www.firewalls.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/sonicwall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.firewalls.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Firewalls","item":"https:\/\/www.firewalls.com\/blog\/category\/firewalls\/"},{"@type":"ListItem","position":3,"name":"SonicWall"}]},{"@type":"WebSite","@id":"https:\/\/www.firewalls.com\/blog\/#website","url":"https:\/\/www.firewalls.com\/blog\/","name":"Firewalls.com","description":"Your Home For Cyber Security News, Stories, &amp; Tutorials","publisher":{"@id":"https:\/\/www.firewalls.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.firewalls.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.firewalls.com\/blog\/#organization","name":"Firewalls.com","url":"https:\/\/www.firewalls.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.firewalls.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.firewalls.com\/blog\/wp-content\/uploads\/2017\/08\/BrandedLogo-TagLineBelow.png","contentUrl":"https:\/\/www.firewalls.com\/blog\/wp-content\/uploads\/2017\/08\/BrandedLogo-TagLineBelow.png","width":365,"height":85,"caption":"Firewalls.com"},"image":{"@id":"https:\/\/www.firewalls.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/firewallscom","https:\/\/x.com\/firewallscom","https:\/\/www.linkedin.com\/company-beta\/1439857\/","https:\/\/www.youtube.com\/user\/firewallsDotCom"]}]}},"_links":{"self":[{"href":"https:\/\/www.firewalls.com\/blog\/wp-json\/wp\/v2\/categories\/598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.firewalls.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.firewalls.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.firewalls.com\/blog\/wp-json\/wp\/v2\/categories\/597"}],"wp:post_type":[{"href":"https:\/\/www.firewalls.com\/blog\/wp-json\/wp\/v2\/posts?categories=598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}